{"id":103,"count":41,"description":"","link":"https:\/\/www.design-ac.net\/articles\/category\/popular\/","name":"\u4eba\u6c17\u8a18\u4e8b","slug":"popular","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.design-ac.net\/articles\/wp-json\/wp\/v2\/categories\/103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.design-ac.net\/articles\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.design-ac.net\/articles\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.design-ac.net\/articles\/wp-json\/wp\/v2\/posts?categories=103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}